{"id":73981,"date":"2026-05-11T10:32:22","date_gmt":"2026-05-11T08:32:22","guid":{"rendered":"https:\/\/fedil.lu\/events\/conference-financement-de-lindustrie-investissements-exportations-technologie-transition-energetique\/"},"modified":"2026-05-11T10:32:22","modified_gmt":"2026-05-11T08:32:22","slug":"conference-financement-de-lindustrie-investissements-exportations-technologie-transition-energetique","status":"publish","type":"event","link":"https:\/\/fedil.lu\/en\/events\/conference-financement-de-lindustrie-investissements-exportations-technologie-transition-energetique\/","title":{"rendered":"Conf\u00e9rence \u00ab FINANCEMENT DE L\u2019INDUSTRIE &#8211; Investissements, Exportations, Technologie, Transition \u00e9nerg\u00e9tique \u00bb"},"content":{"rendered":"<div class=\"text-block js-section\">\n    <h2 class=\"text-block__title\" data-page-navigation=\"\">\n        \n    <\/h2>\n    <div class=\"text-block__text format-text\">\n        <p>Sans capacit\u00e9 d\u2019investir, il n\u2019y a ni transformation, ni d\u00e9carbonation, ni digitalisation. Or, la capacit\u00e9 d\u2019investir est directement li\u00e9e \u00e0 la question du financement.<\/p>\n<p>Si, au Luxembourg, nous disposons d\u2019une panoplie d\u2019instruments de financement puissants et flexibles \u00e0 c\u00f4t\u00e9 d\u2019incitants fiscaux, les entreprises industrielles ignorent trop souvent les intervenants sur le terrain et la port\u00e9e de leurs outils.<\/p>\n<p>Souhaitant mieux promouvoir ces instruments aupr\u00e8s de nos membres, la FEDIL a le plaisir de vous convier \u00e0 sa conf\u00e9rence <strong>\u00ab Financement de l\u2019industrie \u00bb<\/strong> qui se tiendra le <strong>lundi 1er juin 2026 \u00e0 15h00 <\/strong>au<strong> Centre de Conf\u00e9rence de la Chambre de Commerce (salle C2)<\/strong>, en pr\u00e9sence de <strong>Lex Delles<\/strong>, ministre de l&#8217;\u00c9conomie, des PME, de l&#8217;\u00c9nergie et du Tourisme, et de <strong>Gilles Roth<\/strong>, ministre des Finances.<\/p>\n<p>Autour des grands volets <em>\u00ab Investissements, Exportations, Technologie et Transition \u00e9nerg\u00e9tique \u00bb<\/em>, cette conf\u00e9rence r\u00e9unira le Service d\u2019Aides d\u2019\u00c9tat du minist\u00e8re de l&#8217;\u00c9conomie et Luxinnovation, la Soci\u00e9t\u00e9 Nationale de Cr\u00e9dit et d\u2019Investissement (SNCI), l\u2019Office du Ducroire (ODL) et la Banque europ\u00e9enne d\u2019investissement (groupe BEI) qui pr\u00e9senteront leurs diff\u00e9rents types d\u2019aides et d\u2019instruments.<\/p>\n<p>La conf\u00e9rence sera suivi par une r\u00e9ception de networking.<\/p>\n<p>Nous vous invitons \u00e0 vous inscrire \u00e0 cette s\u00e9ance d\u2019information et d\u2019\u00e9change, en utilisant le <a href=\"https:\/\/assets1-eur.mkt.dynamics.com\/6370a080-ff97-4a3e-81ac-db86fccd7bd9\/digitalassets\/standaloneforms\/32093572-8647-f111-bec6-7c1e5270c2f0?readableEventId=CONFRENCE_-_FINANCEMENT_DE_LINDUSTRIE3522029934#_msdynmkt_donottrack=0,_msdynmkt_fn=ICI,_msdynmkt_linkid=2482344c-2233-4503-8199-fa9dc3a2d931\"><strong>lien suivant<\/strong><\/a> avant le 27 mai 2026. Les pr\u00e9sentations se feront en langue fran\u00e7aise.<\/p>\n<p><strong>PROGRAMME<\/strong><\/p>\n<p><em>14h40 Accueil des participants<\/em><\/p>\n<p><strong>15h00 Partie I<\/strong><\/p>\n<ul>\n<li>Bienvenue par Alex Schumann, Pr\u00e9sident de la FEDIL<\/li>\n<li>Mot d\u2019introduction par Gilles Roth, ministre des Finances<\/li>\n<li>Les diff\u00e9rents types d\u2019aides d\u2019\u00c9tat g\u00e9r\u00e9es par le minist\u00e8re de l\u2019\u00c9conomie\n<ul>\n<li><em>Sophie Klecker, Responsable Aides RDI, minist\u00e8re de l&#8217;\u00c9conomie<\/em><\/li>\n<li><em>Rapha\u00ebl Vertommen, Responsable Aides Transition \u00c9cologique, minist\u00e8re de l&#8217;\u00c9conomie<\/em><\/li>\n<li><em>Avit Blanchy, Responsable Financements Nationaux, Luxinnovation<\/em><\/li>\n<\/ul>\n<\/li>\n<li>Les instruments de la SNCI\n<ul>\n<li><em>Eva Kremer, Directeur, Soci\u00e9t\u00e9 Nationale de Cr\u00e9dit et d\u2019Investissement<\/em><\/li>\n<\/ul>\n<\/li>\n<\/ul>\n<p><em>Vers 16h00 Pause-caf\u00e9<\/em><\/p>\n<p><strong>16h20 Partie II<\/strong><\/p>\n<ul>\n<li>L\u2019ODL au service des exportateurs\n<ul>\n<li><em>Danielle Wirtz, Directeur g\u00e9n\u00e9ral adjoint, Office du Ducroire<\/em><\/li>\n<\/ul>\n<\/li>\n<li>Soutien financier et conseil du Groupe BEI\n<ul>\n<li><em>Shiva Dustdar, Director for EIB Group Relations with Luxembourg<\/em><\/li>\n<li><em>Nathalie Climence, Head of Division of Corporates &#8211; Western Europe, EIB<\/em><\/li>\n<li><em>Guy Hudson, Senior Advisory expert, EIB<\/em><\/li>\n<\/ul>\n<\/li>\n<li>Questions-r\u00e9ponses<\/li>\n<li>Mot de cl\u00f4ture par Lex Delles, ministre de l&#8217;\u00c9conomie, des PME, de l&#8217;\u00c9nergie et du Tourisme.<\/li>\n<\/ul>\n<p><em>17h30 R\u00e9ception &amp; networking<\/em><\/p>\n<p>&nbsp;<\/p>\n<p>Dans l&#8217;attente de vous accueillir nombreux, veuillez recevoir, cher membre, Madame, Monsieur, nos salutations chaleureuses !<\/p>\n\n    <\/div>\n<\/div>","protected":false},"excerpt":{"rendered":"","protected":false},"author":14,"featured_media":73969,"template":"","event_category":[1476,715],"class_list":["post-73981","event","type-event","status-publish","has-post-thumbnail","hentry","event_category-members-only-en","event_category-other-topics-en"],"acf":[],"_links":{"self":[{"href":"https:\/\/fedil.lu\/en\/wp-json\/wp\/v2\/event\/73981","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/fedil.lu\/en\/wp-json\/wp\/v2\/event"}],"about":[{"href":"https:\/\/fedil.lu\/en\/wp-json\/wp\/v2\/types\/event"}],"author":[{"embeddable":true,"href":"https:\/\/fedil.lu\/en\/wp-json\/wp\/v2\/users\/14"}],"version-history":[{"count":0,"href":"https:\/\/fedil.lu\/en\/wp-json\/wp\/v2\/event\/73981\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/fedil.lu\/en\/wp-json\/wp\/v2\/media\/73969"}],"wp:attachment":[{"href":"https:\/\/fedil.lu\/en\/wp-json\/wp\/v2\/media?parent=73981"}],"wp:term":[{"taxonomy":"event_category","embeddable":true,"href":"https:\/\/fedil.lu\/en\/wp-json\/wp\/v2\/event_category?post=73981"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}