{"id":50015,"date":"2022-03-04T14:36:02","date_gmt":"2022-03-04T13:36:02","guid":{"rendered":"https:\/\/fedil.lu\/members\/1f085bb5-ece6-e611-80f5-c4346bac8ce8\/"},"modified":"2026-05-13T11:51:42","modified_gmt":"2026-05-13T09:51:42","slug":"1f085bb5-ece6-e611-80f5-c4346bac8ce8","status":"publish","type":"member","link":"https:\/\/fedil.lu\/en\/members\/1f085bb5-ece6-e611-80f5-c4346bac8ce8\/","title":{"rendered":"CLdN RoRo S.A."},"template":"","class_list":["post-50015","member","type-member","status-publish","hentry","member_branch-4c6f88f8-66c7-e611-80f6-c4346bac0ff4-en"],"acf":[],"_links":{"self":[{"href":"https:\/\/fedil.lu\/en\/wp-json\/wp\/v2\/member\/50015","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/fedil.lu\/en\/wp-json\/wp\/v2\/member"}],"about":[{"href":"https:\/\/fedil.lu\/en\/wp-json\/wp\/v2\/types\/member"}],"wp:attachment":[{"href":"https:\/\/fedil.lu\/en\/wp-json\/wp\/v2\/media?parent=50015"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}