{"id":50562,"date":"2022-03-04T14:47:15","date_gmt":"2022-03-04T13:47:15","guid":{"rendered":"https:\/\/fedil.lu\/members\/17155bb5-ece6-e611-80f5-c4346bac8ce8\/"},"modified":"2026-05-13T11:57:27","modified_gmt":"2026-05-13T09:57:27","slug":"17155bb5-ece6-e611-80f5-c4346bac8ce8","status":"publish","type":"member","link":"https:\/\/fedil.lu\/en\/members\/17155bb5-ece6-e611-80f5-c4346bac8ce8\/","title":{"rendered":"Telkea ICT S.A."},"template":"","class_list":["post-50562","member","type-member","status-publish","hentry","member_branch-5c6f88f8-66c7-e611-80f6-c4346bac0ff4-en"],"acf":[],"_links":{"self":[{"href":"https:\/\/fedil.lu\/en\/wp-json\/wp\/v2\/member\/50562","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/fedil.lu\/en\/wp-json\/wp\/v2\/member"}],"about":[{"href":"https:\/\/fedil.lu\/en\/wp-json\/wp\/v2\/types\/member"}],"wp:attachment":[{"href":"https:\/\/fedil.lu\/en\/wp-json\/wp\/v2\/media?parent=50562"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}