{"id":37176,"date":"2021-08-25T10:30:00","date_gmt":"2021-08-25T08:30:00","guid":{"rendered":"https:\/\/fedil.lu\/press-releases\/declaration-de-paris-sur-le-renforcement-de-la-francophonie-economique\/"},"modified":"2021-08-25T10:30:00","modified_gmt":"2021-08-25T08:30:00","slug":"declaration-de-paris-sur-le-renforcement-de-la-francophonie-economique","status":"publish","type":"press-release","link":"https:\/\/fedil.lu\/en\/press-releases\/declaration-de-paris-sur-le-renforcement-de-la-francophonie-economique\/","title":{"rendered":"D\u00e9claration de Paris sur le renforcement de la francophonie \u00e9conomique"},"content":{"rendered":"<div class=\"text-block js-section\">\n    <h2 class=\"text-block__title\" data-page-navigation=\"\">\n        \n    <\/h2>\n    <div class=\"text-block__text format-text\">\n        <p>Les 24 et 25 ao\u00fbt 2021, la FEDIL a particip\u00e9 \u00e0 la premi\u00e8re \u00e9dition de la <strong>Rencontre des Entrepreneurs Francophones (REF)<\/strong>. Suite \u00e0 deux journ\u00e9es de discussions et d\u2019\u00e9changes entre entrepreneurs francophones, les organisations patronales francophones ont sign\u00e9 une d\u00e9claration commune afin de renforcer les liens de la francophonie \u00e9conomique pour une structuration plus profonde de nos actions \u00e0 terme.<\/p>\n<p style=\"text-align: center;\"><a href=\"https:\/\/www.fedil.lu\/wp-content\/uploads\/2021\/08\/DECLARATION-FRANCOPHONIE-SIGNEE.pdf\"><strong>LIRE LA D\u00c9CLARATION<\/strong><\/a><\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-24148\" src=\"https:\/\/www.fedil.lu\/wp-content\/uploads\/2021\/08\/REF21_01-scaled.jpg\" alt=\"\" width=\"2560\" height=\"1920\" \/><br \/>\n<img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-24145\" src=\"https:\/\/www.fedil.lu\/wp-content\/uploads\/2021\/08\/REF21_03-scaled.jpg\" alt=\"\" width=\"2560\" height=\"1920\" \/><\/p>\n\n    <\/div>\n<\/div>","protected":false},"excerpt":{"rendered":"","protected":false},"author":14,"featured_media":0,"template":"","class_list":["post-37176","press-release","type-press-release","status-publish","hentry"],"acf":[],"_links":{"self":[{"href":"https:\/\/fedil.lu\/en\/wp-json\/wp\/v2\/press-release\/37176","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/fedil.lu\/en\/wp-json\/wp\/v2\/press-release"}],"about":[{"href":"https:\/\/fedil.lu\/en\/wp-json\/wp\/v2\/types\/press-release"}],"author":[{"embeddable":true,"href":"https:\/\/fedil.lu\/en\/wp-json\/wp\/v2\/users\/14"}],"version-history":[{"count":0,"href":"https:\/\/fedil.lu\/en\/wp-json\/wp\/v2\/press-release\/37176\/revisions"}],"wp:attachment":[{"href":"https:\/\/fedil.lu\/en\/wp-json\/wp\/v2\/media?parent=37176"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}