{"id":48945,"date":"2022-03-04T11:29:30","date_gmt":"2022-03-04T10:29:30","guid":{"rendered":"https:\/\/fedil.lu\/members\/7f0f5bb5-ece6-e611-80f5-c4346bac8ce8-fr\/"},"modified":"2026-05-13T11:54:46","modified_gmt":"2026-05-13T09:54:46","slug":"7f0f5bb5-ece6-e611-80f5-c4346bac8ce8","status":"publish","type":"member","link":"https:\/\/fedil.lu\/fr\/members\/7f0f5bb5-ece6-e611-80f5-c4346bac8ce8\/","title":{"rendered":"LuxEnergie S.A."},"template":"","class_list":["post-48945","member","type-member","status-publish","hentry","member_branch-2c6f88f8-66c7-e611-80f6-c4346bac0ff4-fr"],"acf":[],"_links":{"self":[{"href":"https:\/\/fedil.lu\/fr\/wp-json\/wp\/v2\/member\/48945","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/fedil.lu\/fr\/wp-json\/wp\/v2\/member"}],"about":[{"href":"https:\/\/fedil.lu\/fr\/wp-json\/wp\/v2\/types\/member"}],"wp:attachment":[{"href":"https:\/\/fedil.lu\/fr\/wp-json\/wp\/v2\/media?parent=48945"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}