{"id":49431,"date":"2022-03-04T11:30:54","date_gmt":"2022-03-04T10:30:54","guid":{"rendered":"https:\/\/fedil.lu\/members\/0d165bb5-ece6-e611-80f5-c4346bac8ce8-fr\/"},"modified":"2026-05-13T11:58:02","modified_gmt":"2026-05-13T09:58:02","slug":"0d165bb5-ece6-e611-80f5-c4346bac8ce8","status":"publish","type":"member","link":"https:\/\/fedil.lu\/fr\/members\/0d165bb5-ece6-e611-80f5-c4346bac8ce8\/","title":{"rendered":"Villeroy &#038; Boch S.\u00e0 r.l."},"template":"","class_list":["post-49431","member","type-member","status-publish","hentry","member_branch-566f88f8-66c7-e611-80f6-c4346bac0ff4-fr"],"acf":[],"_links":{"self":[{"href":"https:\/\/fedil.lu\/fr\/wp-json\/wp\/v2\/member\/49431","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/fedil.lu\/fr\/wp-json\/wp\/v2\/member"}],"about":[{"href":"https:\/\/fedil.lu\/fr\/wp-json\/wp\/v2\/types\/member"}],"wp:attachment":[{"href":"https:\/\/fedil.lu\/fr\/wp-json\/wp\/v2\/media?parent=49431"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}